{"id":7199,"date":"2015-04-23T08:01:27","date_gmt":"2015-04-23T08:01:27","guid":{"rendered":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/"},"modified":"2024-05-28T22:57:05","modified_gmt":"2024-05-28T20:57:05","slug":"nuevas-acciones-contra-rato","status":"publish","type":"post","link":"https:\/\/www.revistarambla.com\/en\/nuevas-acciones-contra-rato\/","title":{"rendered":"Nuevas acciones contra Rato"},"content":{"rendered":"<p>El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles en rueda de prensa en <a href=\"https:\/\/www.revistarambla.com\/en\/actualidad\/barcelona\/\">Barcelona<\/a> una serie de nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato. El grupo ciudadano que en mayo 2012 inici\u00f3 la acci\u00f3n contra Rodrigo Rato y los responsables de la crisis, ha anunciado las siguientes dos lineas de acci\u00f3n en el caso Bankia: \u00abRato NO actuaba solo, vamos a por sus c\u00f3mplices, comenzando por la Agencia Tributaria\u00bb y \u00abAcabemos lo que hemos empezado: tal y como pedimos en un comienzo, esta ma\u00f1ana hemos solicitado de nuevo al juez #carcelpaRato\u00bb.<\/p>\n<h2>15MpaRato, lineas de acci\u00f3n<\/h2>\n<p>La primera de las dos l\u00edneas de acci\u00f3n explicitadas por 15MpaRato apunta a la solicitud de nuevas diligencias de pruebas debido a graves omisiones por parte de la Agencia Tributaria,\u00a0 tras pedir la imputaci\u00f3n de Deloitte y la expulsi\u00f3n del FROB de la causa. \u00ab\u00bfQu\u00e9 tiene que esconder la Agencia Tributaria si ante la petici\u00f3n del juez de \u201clos expedientes abiertos a Bankia y cualquier actuaci\u00f3n\u00a0 realizada\u00bb para comprobar si desde la c\u00fapula de Hacienda se consinti\u00f3 la trama de las Tarjetas Black, env\u00eda la informaci\u00f3n requerida de forma gravemente an\u00f3mala e incompleta?\u00bb, advierten los portavoces del colectivo ciudadano.<\/p>\n<p>\u00abPedimos, para arrojar luz sobre este hecho, la comparecencia como testigos de varios inspectores de Hacienda responsables clave de esas actuaciones fiscales\u00bb, puntualizan.<\/p>\n<p>En segundo lugar, 15MpaRato solicita nuevamente al juez c\u00e1rcel para el ex vicepresidente <a href=\"https:\/\/www.revistarambla.com\/en\/colapso-bancario\/\">Rodrigo Rato<\/a> por fraude mientras estaba al mando de Bankia. \u00abLa\u00a0 impunidad de Rodrigo Rato, tal y como anunciamos hace tres a\u00f1os, se ha acabado. La\u00a0 monta\u00f1a que hemos erosionado se derrumba ahora de golpe por el peso de las evidencias que hemos aportado durante estos a\u00f1os\u00bb, aclaman desde la plataforma.<\/p>\n<p>\u00abSe confirma ahora que las contradicciones en el interrogatorio &#8211; la tercera vez que conseguimos sentar a Rato en el banquillo tras destapar las Tarjetas Negras &#8211; pusieron a Hacienda sobre su pista y que la fianza hist\u00f3rica de 800 millones de euros a Bankia por la acusaci\u00f3n de falsedad documental que solo estaba en nuestra querella, le puso lo suficientemente nervioso como para hacerle cometer muchos errores a la hora de poner a buen recaudo en para\u00edsos fiscales el bot\u00edn que hab\u00eda acumulado durante estos a\u00f1os\u00bb, detallan.<\/p>\n<p>\u00abLa ca\u00edda de Rato es una victoria colectiva de la ciudadan\u00eda organizada que debemos celebrar, pero nunca fue un objetivo personal para nosotros sino un objetivo estrat\u00e9gico. No es el final de nada, pero lo cambia todo\u00bb, anuncia 15MpaRato que, tambi\u00e9n, hace hincapi\u00e9 en que para llevar a cabo la estafa millonaria fue necesaria la participaci\u00f3n de, adem\u00e1s de los responsables, varios c\u00f3mplices dentro del Gobierno. \u00abNo es ning\u00fan secreto que tanto de Guindos como Montoro, que ahora pretenden\u00a0 presentarse como los verdugos de Rato, fueron durante a\u00f1os sus\u00a0 subordinados, sus c\u00f3mplices, as\u00ed que tendr\u00e1n que responder\u00bb, advierten.<\/p>\n<p>En este sentido, el colectivo 15MpaRato, en la presentaci\u00f3n ante la prensa ha tirado de otro hilo: \u00abes menos conocido que la directora de la Agencia Tributaria que fren\u00f3 la investigacion sobre qu\u00e9 cargos y excargos del estado se habian acogido a la anmisit\u00eda fiscal, Beatriz Viana, fue empleada y jefa de gabinete de Rato y ahora es la presidenta de la CNMV\u00bb, anuncian los portavoces de la plataforma.<\/p>\n<p>\u00abDe hecho, la principal l\u00ednea de defensa de Rato en la causa que hemos abierto tras destapar las Tarjetas Black es precisamente que Hacienda estaba al tanto de todo. Esta manera de decir \u00absi caigo yo caer\u00e9is conmigo\u00bb no ha sido la \u00fanica amenaza de Rato que ha motivado que sus antiguos c\u00f3mplices que controlan estas instituciones lo tuvieran que dejar caer\u00bb, explican.<\/p>\n<p>La Agencia Tributaria deber\u00eda ser la primera interesada en aclarar si existi\u00f3 complicidad entre su c\u00fapula, que Rato control\u00f3\u00a0 durante a\u00f1os, y el entramado de las Tarjetas Black. Pero percibimos claros indicios de que esto no es as\u00ed.<\/p>\n<p>Pero los ciudadanos no somos expectadores pasivos de esta trama. Gracias a que la ciudadan\u00eda organizada en la Comisi\u00f3n Anticorrupci\u00f3n del Partido X hizo llegar a la\u00a0 prensa los Correos de Blesa y al trabajo de 15MpaRato, que consigui\u00f3 que la trama de las\u00a0 Tarjetas Negras llegara a la justicia, podemos encontrar evidencias de la connivencia entre la c\u00fapula de Hacienda y la Bankia de Blesa y Rato en dichos correos.<\/p>","protected":false},"excerpt":{"rendered":"<p>El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles en rueda de prensa en Barcelona una serie de nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato. El grupo ciudadano que en mayo 2012 inici\u00f3 la acci\u00f3n contra Rodrigo Rato y los responsables de la crisis, ha anunciado las siguientes dos lineas de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-7199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barcelona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevas acciones contra Rato - Revista Rambla<\/title>\n<meta name=\"description\" content=\"El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistarambla.com\/en\/nuevas-acciones-contra-rato\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevas acciones contra Rato - Revista Rambla\" \/>\n<meta property=\"og:description\" content=\"El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistarambla.com\/en\/nuevas-acciones-contra-rato\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Rambla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revistarambla\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revistarambla\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-23T08:01:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T20:57:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2015\/04\/15MpaRato_revRambla02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t<meta property=\"og:image:height\" content=\"276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R@mbla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistarambla\" \/>\n<meta name=\"twitter:site\" content=\"@revistarambla\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"R@mbla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/\"},\"author\":{\"name\":\"R@mbla\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/person\\\/a146a5a2550b94981a75131180e1bd9c\"},\"headline\":\"Nuevas acciones contra Rato\",\"datePublished\":\"2015-04-23T08:01:27+00:00\",\"dateModified\":\"2024-05-28T20:57:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/\"},\"wordCount\":761,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/15MpaRato_revRambla02.jpg\",\"articleSection\":[\"Barcelona\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/\",\"name\":\"Nuevas acciones contra Rato - Revista Rambla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/15MpaRato_revRambla02.jpg\",\"datePublished\":\"2015-04-23T08:01:27+00:00\",\"dateModified\":\"2024-05-28T20:57:05+00:00\",\"description\":\"El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/15MpaRato_revRambla02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/15MpaRato_revRambla02.jpg\",\"width\":525,\"height\":276,\"caption\":\"Colectivo 15MpaRato cartel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/nuevas-acciones-contra-rato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.revistarambla.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevas acciones contra Rato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#website\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/\",\"name\":\"Revista Rambla Barcelona\",\"description\":\"Periodismo independiente\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistarambla.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\",\"name\":\"Revista Rambla\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/banner_rambla_1900x600_BB.png\",\"contentUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/banner_rambla_1900x600_BB.png\",\"width\":1900,\"height\":600,\"caption\":\"Revista Rambla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revistarambla\\\/\",\"https:\\\/\\\/x.com\\\/revistarambla\",\"https:\\\/\\\/www.instagram.com\\\/revista_rambla\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/revista-rambla\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/person\\\/a146a5a2550b94981a75131180e1bd9c\",\"name\":\"R@mbla\",\"description\":\"Este art\u00edculo ha sido redactado y\\\/o validado por el equipo de redacci\u00f3n de Revista Rambla.\",\"sameAs\":[\"https:\\\/\\\/www.revistarambla.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/revistarambla\",\"https:\\\/\\\/x.com\\\/revistarambla\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevas acciones contra Rato - Revista Rambla","description":"El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistarambla.com\/en\/nuevas-acciones-contra-rato\/","og_locale":"en_GB","og_type":"article","og_title":"Nuevas acciones contra Rato - Revista Rambla","og_description":"El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato.","og_url":"https:\/\/www.revistarambla.com\/en\/nuevas-acciones-contra-rato\/","og_site_name":"Revista Rambla","article_publisher":"https:\/\/www.facebook.com\/revistarambla\/","article_author":"https:\/\/www.facebook.com\/revistarambla","article_published_time":"2015-04-23T08:01:27+00:00","article_modified_time":"2024-05-28T20:57:05+00:00","og_image":[{"width":525,"height":276,"url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2015\/04\/15MpaRato_revRambla02.jpg","type":"image\/jpeg"}],"author":"R@mbla","twitter_card":"summary_large_image","twitter_creator":"@revistarambla","twitter_site":"@revistarambla","twitter_misc":{"Written by":"R@mbla","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#article","isPartOf":{"@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/"},"author":{"name":"R@mbla","@id":"https:\/\/www.revistarambla.com\/#\/schema\/person\/a146a5a2550b94981a75131180e1bd9c"},"headline":"Nuevas acciones contra Rato","datePublished":"2015-04-23T08:01:27+00:00","dateModified":"2024-05-28T20:57:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/"},"wordCount":761,"commentCount":0,"publisher":{"@id":"https:\/\/www.revistarambla.com\/#organization"},"image":{"@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2015\/04\/15MpaRato_revRambla02.jpg","articleSection":["Barcelona"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/","url":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/","name":"Nuevas acciones contra Rato - Revista Rambla","isPartOf":{"@id":"https:\/\/www.revistarambla.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#primaryimage"},"image":{"@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2015\/04\/15MpaRato_revRambla02.jpg","datePublished":"2015-04-23T08:01:27+00:00","dateModified":"2024-05-28T20:57:05+00:00","description":"El colectivo 15MpaRato ha anunciado este mi\u00e9rcoles nuevas acciones en la campa\u00f1a que denominan\u00a0 #C\u00f3mplicesPaRato.","breadcrumb":{"@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#primaryimage","url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2015\/04\/15MpaRato_revRambla02.jpg","contentUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2015\/04\/15MpaRato_revRambla02.jpg","width":525,"height":276,"caption":"Colectivo 15MpaRato cartel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistarambla.com\/nuevas-acciones-contra-rato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistarambla.com\/"},{"@type":"ListItem","position":2,"name":"Nuevas acciones contra Rato"}]},{"@type":"WebSite","@id":"https:\/\/www.revistarambla.com\/#website","url":"https:\/\/www.revistarambla.com\/","name":"Revista Rambla Barcelona","description":"Periodismo independiente","publisher":{"@id":"https:\/\/www.revistarambla.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistarambla.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.revistarambla.com\/#organization","name":"Revista Rambla","url":"https:\/\/www.revistarambla.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.revistarambla.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2020\/09\/banner_rambla_1900x600_BB.png","contentUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2020\/09\/banner_rambla_1900x600_BB.png","width":1900,"height":600,"caption":"Revista Rambla"},"image":{"@id":"https:\/\/www.revistarambla.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revistarambla\/","https:\/\/x.com\/revistarambla","https:\/\/www.instagram.com\/revista_rambla","https:\/\/es.linkedin.com\/company\/revista-rambla"]},{"@type":"Person","@id":"https:\/\/www.revistarambla.com\/#\/schema\/person\/a146a5a2550b94981a75131180e1bd9c","name":"R@mbla","description":"Este art\u00edculo ha sido redactado y\/o validado por el equipo de redacci\u00f3n de Revista Rambla.","sameAs":["https:\/\/www.revistarambla.com\/","https:\/\/www.facebook.com\/revistarambla","https:\/\/x.com\/revistarambla"]}]}},"_links":{"self":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/7199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/comments?post=7199"}],"version-history":[{"count":3,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/7199\/revisions"}],"predecessor-version":[{"id":60632,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/7199\/revisions\/60632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/media\/7198"}],"wp:attachment":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/media?parent=7199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/categories?post=7199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/tags?post=7199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}