{"id":4355,"date":"2013-11-28T09:17:04","date_gmt":"2013-11-28T09:17:04","guid":{"rendered":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/"},"modified":"2024-05-13T21:05:31","modified_gmt":"2024-05-13T19:05:31","slug":"curso-acelerado-de-ateismo","status":"publish","type":"post","link":"https:\/\/www.revistarambla.com\/en\/curso-acelerado-de-ateismo\/","title":{"rendered":"Curso acelerado de ate\u00edsmo"},"content":{"rendered":"<p>\u00bfExiste dios? Esta es la primera pregunta del hombre. Y a partir de esta pregunta y al correr de la Historia, aparecer\u00e1 el pensamiento cr\u00edtico, la Filosof\u00eda, quiz\u00e1s todas las ciencias. Hagamos, pues, un curso acelerado de ate\u00edsmo.<\/p>\n<h2>Lecci\u00f3n primera del curso de ate\u00edsmo: el creer en no creer<\/h2>\n<p>Esta pregunta al parecer s\u00f3lo ha sido contestada o respondida de dos maneras, el de\u00edsta dir\u00e1 que s\u00ed, que cree en dios, y el ateo dir\u00e1: \u201cno lo s\u00e9, pero creo que no\u201d. Para el de\u00edsta, que se basa en la fe, no hay ning\u00fan problema; para el ateo, que se basa en la raz\u00f3n, su respuesta ha de ser matizada porque creer en un no-creer pide reflexi\u00f3n.<\/p>\n<p>Y la reflexi\u00f3n consiste en que se ha de considerar la imposibilidad de demostrar la inexistencia de algo. Claro que si una existencia puede ser demostrada, la creencia en su no existencia caer\u00eda por su base.<\/p>\n<p>Y aqu\u00ed empieza el gran problema de los creyentes que hemos llamado de\u00edstas para simplificar. Porque si bien es verdad que es imposible demostrar la no existencia de algo, s\u00ed es posible y hasta muy, pero que muy recomendable, el demostrar su existencia. Y ni cortos ni perezosos, los de\u00edstas se han dedicado durante siglos a demostrar la existencia de dios.<\/p>\n<p>El que existan tantas \u201cpruebas\u201d de la existencia de dios, significa, en un primer momento, que ninguna de las llamadas pruebas ha sido definitiva. Es decir, que ninguna de las pruebas logra su objetivo final: la demostraci\u00f3n de la existencia de dios.<\/p>\n<p>Efectivamente, a partir de la raz\u00f3n no hay posibilidad alguna de demostrar la existencia de Algo que se supone en teor\u00eda o en hip\u00f3tesis. Y no es posible porque no hay manera de llegar a la verificaci\u00f3n de esta existencia supuesta.<\/p>\n<p>La respuesta, ante la falta de pruebas razonables por parte de los creyentes, no se hizo esperar: se trata para los de\u00edstas de una cuesti\u00f3n de fe y de una cuesti\u00f3n de revelaci\u00f3n.<\/p>\n<p>La revelaci\u00f3n consiste en creer, a partir de ciertos textos que no se discuten, que el mismo dios se manifest\u00f3 o revel\u00f3 al hombre. O de otra manera, la revelaci\u00f3n es el acto por el cual un ser supremo desvela, revela su propia existencia a los hombres, ya que, impl\u00edcitamente, se supone que el hombre, por su sola raz\u00f3n, no puede llegar jam\u00e1s a las llamadas verdades reveladas.<\/p>\n<p>Observemos inmediatamente, que se trata, ante todo de separar al hombre de su raz\u00f3n, de su cr\u00edtica, de su pensamiento, no se le pide que piense, al contrario, se le pide que crea, y dios o el supremo hacedor, comprendiendo las limitaciones que ya son prohibiciones del hombre, decide revelarse.<\/p>\n<p>Hay tantas revelaciones como religiones, es decir, existen tantas prohibiciones de pensar con la raz\u00f3n, como religiones existen.<\/p>\n<p>Los dioses se revelan por medio de libros escritos por iluminados o profetas, y los destinatarios de estos libros, han de creer que dios no s\u00f3lo existe, sino que demuestra su existencia a trav\u00e9s de los libros \u201cdictados\u201d a estos hombres escogidos.<\/p>\n<p>La raz\u00f3n cr\u00edtica del hombre, su pensamiento, en resumen, queda arrinconada o arrinconado ante un hecho que no necesita para nada la raz\u00f3n, necesita apelar solamente a la fe del hombre.<\/p>\n<p>Desgraciadamente, para los creyentes, un acto de fe no es un acto de raz\u00f3n, y hay hombres, los ha habido siempre, que se han negado a la fe en nombre precisamente de su raz\u00f3n. Se les llam\u00f3 imp\u00edos, herejes, ateos, agn\u00f3sticos y otros ep\u00edtetos.<\/p>\n<p>Que al hombre no le bastaba la fe para creer, es un hecho que se demuestra por la necesaria existencia de la revelaci\u00f3n. Las religiones comprendieron enseguida que el hombre no se sujeta a la fe predicada tan simplemente, entonces surgi\u00f3 la revelaci\u00f3n, es decir, la afirmaci\u00f3n por escrito de la fe del hombre.<\/p>\n<p>La existencia, pues, de una revelaci\u00f3n divina demuestra que no s\u00f3lo por la raz\u00f3n, sino que ni siquiera por la fe, es posible creer en la existencia de un ser supremo.<\/p>\n<p>Si bastara la fe, no se necesitar\u00eda ninguna revelaci\u00f3n. Al parecer dios preocupad\u00edsimo por la falta de fe de los hombres, no tuvo m\u00e1s remedio que escribir sobre su propia existencia. Es el \u00abyo soy el que soy\u00bb de la <a href=\"https:\/\/www.revistarambla.com\/en\/la-biblia-decadente-de-huysmans\/\">Biblia<\/a>, es el autoproclamarse dios \u00fanico en la mayor parte de los textos de diversas religiones.<\/p>\n<p>Apelando a la raz\u00f3n del hombre, no es posible demostrar la existencia de dios, entonces se ech\u00f3 mano de la fe y de la revelaci\u00f3n. El que, m\u00e1s tarde, se pudiera demostrar, por la raz\u00f3n, que las revelaciones no pasan de ser obra humana, oblig\u00f3 a las revelaciones a fortificarse en la fe. Y con la fe no se demuestra nada, pero se cree en la existencia de algo que no se puede demostrar.<\/p>\n<p>Desgraciadamente, para el ateo, la fe no puede ser cre\u00edda, por eso si labor intelectual consiste en creer, dar por verdadero, el no creer. A la pregunta de si existe dios, el ateo razonable, cr\u00edtico y simplemente humano, responde en un primer momento, no lo s\u00e9, creo que no. Claro que si se trata de un ateo bien educado, es decir, no excesivamente duro ante el creyente, responder\u00e1: no lo s\u00e9, creo que no, aunque espero que por su bien, por el creyente, que se demuestre alg\u00fan d\u00eda.<\/p>\n<p>Hoy por hoy, el creyente lleva siglos \u201cdemostrando\u201d la existencia de dios y esta existencia no ha podido ser probada. El creyente replicar\u00e1, quiz\u00e1s ya un poco enfadado: de acuerdo no puedo demostrar la existencia de dios, pero t\u00fa, ateo, tampoco puedes demostrar su inexistencia. Lo cual es cierto.<\/p>\n<p>Para volver al principio, si efectivamente la no existencia de algo es indemostrable por definici\u00f3n, el ateo ha de responder ante la gran pregunta con el no s\u00e9.<\/p>\n<p>Respuesta a primera vista neutra y muy poco beligerante, pero que si se medita, es toda una declaraci\u00f3n racional, digna del hombre. O para decirlo con Epicuro: hay que respetar a los dioses aunque no se crea en ellos. Por eso el ateo no es un imp\u00edo ni un blasfemo (\u00bfc\u00f3mo maldecir de lo inexistente?) sino un hombre que quiere seguir pensando.<\/p>\n<h2>Lecci\u00f3n segunda: la primera obligaci\u00f3n del ateo ha de consistir en creer en todos los dioses<\/h2>\n<p>El t\u00edtulo de la presente lecci\u00f3n del curso acelerado de ate\u00edsmo puede parecer parad\u00f3jico; sin embargo, hay que pensar que s\u00f3lo creyendo en la existencia de todos los dioses, es posible el ate\u00edsmo.<\/p>\n<p>Esta existencia de los dioses que cree el ateo, se refiere, como es l\u00f3gico, a su existencia hist\u00f3rica, real. Todos los dioses que conocemos han tenido historia, tiempo y espacio, y mal que les pese a los creyentes, tambi\u00e9n han tenido un principio.<\/p>\n<p>El ateo cree firmemente que la necesidad llev\u00f3 al hombre a la creaci\u00f3n de los dioses. O de otra manera, que ning\u00fan dios tiene una existencia gratuita. Buscar la explicaci\u00f3n de esta necesidad de dotarse de dioses, est\u00e1 en la base de la <a href=\"https:\/\/www.revistarambla.com\/en\/cultura\/historia\/\">Historia<\/a> de las Religiones\u2026<\/p>\n<p><em>Curso acelerado de ate\u00edsmo, Antonio L\u00f3pez Campillo y Juan Ignacio Ferreras. Colecci\u00f3n \u201cLa nave de los locos\u201d, ed. VOSA. Madrid, 1996.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfExiste dios? Esta es la primera pregunta del hombre. Y a partir de esta pregunta y al correr de la Historia, aparecer\u00e1 el pensamiento cr\u00edtico, la Filosof\u00eda, quiz\u00e1s todas las ciencias. Hagamos, pues, un curso acelerado de ate\u00edsmo. Lecci\u00f3n primera del curso de ate\u00edsmo: el creer en no creer Esta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-4355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curso acelerado de ate\u00edsmo - Revista Rambla<\/title>\n<meta name=\"description\" content=\"Lecci\u00f3n del curso acelerado de ate\u00edsmo: la primera obligaci\u00f3n del ateo ha de consistir en creer en todos los dioses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistarambla.com\/en\/curso-acelerado-de-ateismo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso acelerado de ate\u00edsmo - Revista Rambla\" \/>\n<meta property=\"og:description\" content=\"Lecci\u00f3n del curso acelerado de ate\u00edsmo: la primera obligaci\u00f3n del ateo ha de consistir en creer en todos los dioses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistarambla.com\/en\/curso-acelerado-de-ateismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Rambla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revistarambla\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revistarambla\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-28T09:17:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-13T19:05:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2013\/11\/cristianos_rambla_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R@mbla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistarambla\" \/>\n<meta name=\"twitter:site\" content=\"@revistarambla\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"R@mbla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/\"},\"author\":{\"name\":\"R@mbla\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/person\\\/a146a5a2550b94981a75131180e1bd9c\"},\"headline\":\"Curso acelerado de ate\u00edsmo\",\"datePublished\":\"2013-11-28T09:17:04+00:00\",\"dateModified\":\"2024-05-13T19:05:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/\"},\"wordCount\":1272,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/cristianos_rambla_02.jpg\",\"articleSection\":[\"Libros\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/\",\"name\":\"Curso acelerado de ate\u00edsmo - Revista Rambla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/cristianos_rambla_02.jpg\",\"datePublished\":\"2013-11-28T09:17:04+00:00\",\"dateModified\":\"2024-05-13T19:05:31+00:00\",\"description\":\"Lecci\u00f3n del curso acelerado de ate\u00edsmo: la primera obligaci\u00f3n del ateo ha de consistir en creer en todos los dioses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/cristianos_rambla_02.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/cristianos_rambla_02.jpg\",\"width\":700,\"height\":462,\"caption\":\"mano libro curso ate\u00edsmo rosario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/curso-acelerado-de-ateismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.revistarambla.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso acelerado de ate\u00edsmo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#website\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/\",\"name\":\"Revista Rambla Barcelona\",\"description\":\"Periodismo independiente\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistarambla.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\",\"name\":\"Revista Rambla\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/banner_rambla_1900x600_BB.png\",\"contentUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/banner_rambla_1900x600_BB.png\",\"width\":1900,\"height\":600,\"caption\":\"Revista Rambla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revistarambla\\\/\",\"https:\\\/\\\/x.com\\\/revistarambla\",\"https:\\\/\\\/www.instagram.com\\\/revista_rambla\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/revista-rambla\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/person\\\/a146a5a2550b94981a75131180e1bd9c\",\"name\":\"R@mbla\",\"description\":\"Este art\u00edculo ha sido redactado y\\\/o validado por el equipo de redacci\u00f3n de Revista Rambla.\",\"sameAs\":[\"https:\\\/\\\/www.revistarambla.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/revistarambla\",\"https:\\\/\\\/x.com\\\/revistarambla\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso acelerado de ate\u00edsmo - Revista Rambla","description":"Lecci\u00f3n del curso acelerado de ate\u00edsmo: la primera obligaci\u00f3n del ateo ha de consistir en creer en todos los dioses.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistarambla.com\/en\/curso-acelerado-de-ateismo\/","og_locale":"en_GB","og_type":"article","og_title":"Curso acelerado de ate\u00edsmo - Revista Rambla","og_description":"Lecci\u00f3n del curso acelerado de ate\u00edsmo: la primera obligaci\u00f3n del ateo ha de consistir en creer en todos los dioses.","og_url":"https:\/\/www.revistarambla.com\/en\/curso-acelerado-de-ateismo\/","og_site_name":"Revista Rambla","article_publisher":"https:\/\/www.facebook.com\/revistarambla\/","article_author":"https:\/\/www.facebook.com\/revistarambla","article_published_time":"2013-11-28T09:17:04+00:00","article_modified_time":"2024-05-13T19:05:31+00:00","og_image":[{"width":700,"height":462,"url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2013\/11\/cristianos_rambla_02.jpg","type":"image\/jpeg"}],"author":"R@mbla","twitter_card":"summary_large_image","twitter_creator":"@revistarambla","twitter_site":"@revistarambla","twitter_misc":{"Written by":"R@mbla","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#article","isPartOf":{"@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/"},"author":{"name":"R@mbla","@id":"https:\/\/www.revistarambla.com\/#\/schema\/person\/a146a5a2550b94981a75131180e1bd9c"},"headline":"Curso acelerado de ate\u00edsmo","datePublished":"2013-11-28T09:17:04+00:00","dateModified":"2024-05-13T19:05:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/"},"wordCount":1272,"commentCount":0,"publisher":{"@id":"https:\/\/www.revistarambla.com\/#organization"},"image":{"@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2013\/11\/cristianos_rambla_02.jpg","articleSection":["Libros"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/","url":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/","name":"Curso acelerado de ate\u00edsmo - Revista Rambla","isPartOf":{"@id":"https:\/\/www.revistarambla.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#primaryimage"},"image":{"@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2013\/11\/cristianos_rambla_02.jpg","datePublished":"2013-11-28T09:17:04+00:00","dateModified":"2024-05-13T19:05:31+00:00","description":"Lecci\u00f3n del curso acelerado de ate\u00edsmo: la primera obligaci\u00f3n del ateo ha de consistir en creer en todos los dioses.","breadcrumb":{"@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#primaryimage","url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2013\/11\/cristianos_rambla_02.jpg","contentUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2013\/11\/cristianos_rambla_02.jpg","width":700,"height":462,"caption":"mano libro curso ate\u00edsmo rosario"},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistarambla.com\/curso-acelerado-de-ateismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistarambla.com\/"},{"@type":"ListItem","position":2,"name":"Curso acelerado de ate\u00edsmo"}]},{"@type":"WebSite","@id":"https:\/\/www.revistarambla.com\/#website","url":"https:\/\/www.revistarambla.com\/","name":"Revista Rambla Barcelona","description":"Periodismo independiente","publisher":{"@id":"https:\/\/www.revistarambla.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistarambla.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.revistarambla.com\/#organization","name":"Revista Rambla","url":"https:\/\/www.revistarambla.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.revistarambla.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2020\/09\/banner_rambla_1900x600_BB.png","contentUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2020\/09\/banner_rambla_1900x600_BB.png","width":1900,"height":600,"caption":"Revista Rambla"},"image":{"@id":"https:\/\/www.revistarambla.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revistarambla\/","https:\/\/x.com\/revistarambla","https:\/\/www.instagram.com\/revista_rambla","https:\/\/es.linkedin.com\/company\/revista-rambla"]},{"@type":"Person","@id":"https:\/\/www.revistarambla.com\/#\/schema\/person\/a146a5a2550b94981a75131180e1bd9c","name":"R@mbla","description":"Este art\u00edculo ha sido redactado y\/o validado por el equipo de redacci\u00f3n de Revista Rambla.","sameAs":["https:\/\/www.revistarambla.com\/","https:\/\/www.facebook.com\/revistarambla","https:\/\/x.com\/revistarambla"]}]}},"_links":{"self":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/4355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/comments?post=4355"}],"version-history":[{"count":2,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/4355\/revisions"}],"predecessor-version":[{"id":60274,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/4355\/revisions\/60274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/media\/4354"}],"wp:attachment":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/media?parent=4355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/categories?post=4355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/tags?post=4355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}