{"id":11794,"date":"2017-03-02T08:14:19","date_gmt":"2017-03-02T07:14:19","guid":{"rendered":"https:\/\/www.revistarambla.com\/?p=11794"},"modified":"2021-12-20T19:54:15","modified_gmt":"2021-12-20T18:54:15","slug":"pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado","status":"publish","type":"post","link":"https:\/\/www.revistarambla.com\/en\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/","title":{"rendered":"Pere Le\u00f3n: \u00abEntre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\u00bb"},"content":{"rendered":"<p style=\"text-align: left;\">Hace diez a\u00f1os sal\u00eda al mercado el primer Iphone, un dispositivo que pocos podr\u00edan haber imaginado que cambiar\u00eda la sociedad de una forma tan radical como lo ha hecho. Hoy, Espa\u00f1a es l\u00edder mundial en cuota de penetraci\u00f3n de Smartphone. Organismos internacionales han alertado de los m\u00faltiples riesgos que comportan las radiaciones emitidas por las nuevas tecnolog\u00edas, pero no parece que su uso vaya a disminuir. En estos d\u00edas en qu\u00e9 Barcelona acoge el Mobile World Congress, estas preocupaciones vuelven a ser tema central de debate. De ello hablamos con Pere Le\u00f3n, arquitecto y geobi\u00f3logo experto en salud geoambiental.<\/p>\n<p style=\"text-align: left;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-11796\" src=\"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-02.jpg\" alt=\"\" width=\"644\" height=\"362\" srcset=\"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-02.jpg 644w, https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-02-300x169.jpg 300w, https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-02-500x281.jpg 500w\" sizes=\"(max-width: 644px) 100vw, 644px\" \/><\/p>\n<p style=\"text-align: left;\">Pere Le\u00f3n estaba al mando de un estudio de arquitectura en Sabadell antes de descubrir la geobiolog\u00eda, la ciencia que estudia el impacto que las energ\u00edas provocadas por la tierra tienen en el ser humano. Cuando su familia empez\u00f3 a tener problemas de sue\u00f1o, comprob\u00f3 de su propia mano las radiaciones naturales eran la causa, y que adem\u00e1s tambi\u00e9n pueden ser muy perjudiciales las radiaciones artificiales, provocadas por las nuevas tecnolog\u00edas. Desde entonces, en 2006, volc\u00f3 todo su trabajo a esta nueva disciplina, y naci\u00f3 Habitat Salut, Espais Saludables, con el objetivo de \u2018\u2019analizar, proponer y proyectar soluciones y proyectos para adecuar un espacio para que sea bi\u00f3tico, es decir, apto para la vida\u2019\u2019. Adem\u00e1s, Pere Le\u00f3n es tambi\u00e9n el autor de dos libros, <em>La buena onda<\/em> (Grijalbo, 2013) y <em>Vivir en modo avi\u00f3n<\/em> (Urano, 2015), y est\u00e1 trabajando en el tercero.<\/p>\n<p style=\"text-align: left;\"><strong>\u00a0<\/strong><strong>\u00bfC\u00f3mo nos afecta la tecnolog\u00eda f\u00edsicamente?<\/strong><\/p>\n<p style=\"text-align: left;\">La OMS dijo en el a\u00f1o 2011 que las ondas de alta frecuencia, conocidas como radiaciones de telefon\u00eda, eran posibles cancer\u00edgenas, pero no ha habido ratificaci\u00f3n, hay un debate en la sociedad. Sabemos que la presencia de campos magn\u00e9ticos es un potenciador que triplica o cuadriplica la posibilidad de sufrir una leucemia, y que las radiaciones de campo el\u00e9ctrico alteran el ritmo circadiano [ciclo biol\u00f3gico regulador del sue\u00f1o y la vigilia]. Una persona est\u00e1 definida por tres \u00e1reas, la gen\u00e9tica, que representa el 25%, y de la cual forma parte la predisposici\u00f3n a sufrir enfermedades; el estilo de vida, que representa el 45%, y el tercero, que es el sue\u00f1o, con un 30%. Todo empieza con el sue\u00f1o. Cuando vamos a dormir tenemos que darle cuerda a nuestro reloj biol\u00f3gico, y para hacerlo bien tenemos que dormir siempre ocho horas, que la temperatura y el lugar sean los adecuados, y sobretodo no mirar pantallas antes de ir a dormir porque rompen la producci\u00f3n de melatonina, que regula el sue\u00f1o.<\/p>\n<p style=\"text-align: left;\">El perfil de cliente que tenemos en Habitat Salut es aquella persona que despu\u00e9s de haber vivido X a\u00f1os en un sitio donde ha dormido sin problemas, se va a otro sitio y empieza a dormir mal. Aprieta los dientes, se despierta a media noche, est\u00e1 muy cansada, se levanta con dolores articulares y de cabeza, est\u00e1 triste, irritable, o depresiva. Entonces lo que hacemos nosotros es analizar, proponer y proyectar soluciones y proyectos para adecuar espacios para que sean bi\u00f3ticos, aptos para la vida.<\/p>\n<p style=\"text-align: left;\"><strong>Centr\u00e9monos en los dispositivos tecnol\u00f3gicos<\/strong><\/p>\n<p style=\"text-align: left;\">Hay campos magn\u00e9ticos que pueden venir provocados por un radiodespertador enchufado a la corriente, y un Smartphone que tienes al lado de la mesita de noche tiene doble vertiente, porque por un lado est\u00e1 tambi\u00e9n enchufado y por tanto genera un campo el\u00e9ctrico y magn\u00e9tico, y por otro el tel\u00e9fono, si adem\u00e1s tiene los datos activados, est\u00e1 emitiendo ondas que son perjudiciales. As\u00ed, la propuesta saludable es, no duermas con el m\u00f3vil al lado.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfQu\u00e9 hay de las tabletas y los routers?<\/strong><\/p>\n<p style=\"text-align: left;\">Con las tabletas estamos en las mismas que con los Smartphone, y con los routers, que pueden transmitir informaci\u00f3n por cable o de forma inal\u00e1mbrica, que ser\u00eda el wifi, la proximidad del aparato, la intensidad y la modulaci\u00f3n pueden afectarte. Hace poco me encontr\u00e9 con dos ni\u00f1os de 7 y 8 a\u00f1os que se meaban en la cama, y vimos que al otro lado de la pared hab\u00eda un router. Lo apagamos y dejaron de hacerlo. No es el primer caso as\u00ed con el que me encuentro, pero esto no significa que todos reaccionen igual, porque cada uno expresa diferente sintomatolog\u00eda.<\/p>\n<p style=\"text-align: left;\">Hoy tenemos unas herramientas muy buenas para saber si un dispositivo nos afecta o no, pero cuando no tenemos esta certeza est\u00e1 el principio de precauci\u00f3n y el sentido com\u00fan. Es de sentido com\u00fan que no debemos dormir con un m\u00f3vil al lado de la cabeza. Un neur\u00f3logo me dijo que hab\u00eda encontrado j\u00f3venes al borde del derrame cerebral por culpa de esto, adem\u00e1s de que si no duermen acabar\u00e1n petando. Donde dormir para no morir, este es el t\u00edtulo de mi pr\u00f3ximo libro, que est\u00e1 en proceso.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfSon los ni\u00f1os los m\u00e1s afectados?<\/strong><\/p>\n<p style=\"text-align: left;\">S\u00ed, y las personas mayores, porqu\u00e9 son los m\u00e1s vulnerables. El impacto de las radiaciones funciona como detonante de enfermedades. Los ni\u00f1os est\u00e1n en un proceso de crecimiento brutal, y su sistema inmune es muy potente pero a la vez van a una velocidad estrepitosa. Cuando a un ni\u00f1o le diagnostican c\u00e1ncer las c\u00e9lulas cancer\u00edgenas van a toda velocidad. En cuanto al efecto de los campos electromagn\u00e9ticos, los ni\u00f1os tienen la corteza cerebral mucho m\u00e1s delgada y permeable, por lo que les afecta m\u00e1s, y a las personas mayores tambi\u00e9n, porque tienen menos resistencia y aguantan mucho menos los cambios.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfLos nuevos dispositivos tecnol\u00f3gicos son m\u00e1s perjudiciales que los de antes?<\/strong><\/p>\n<p style=\"text-align: left;\">S\u00ed, los de antes eran inofensivos. Uno de los problemas m\u00e1s graves ha sido que con la aparici\u00f3n de la telefon\u00eda m\u00f3vil y el wifi la tecnolog\u00eda se ha vuelto inal\u00e1mbrica. Mientras que la longitud de onda que utiliza una antena de TV para transmitir un mensaje es sinuosa y abarca muchos kil\u00f3metros, aunque lleva poca informaci\u00f3n, cuando la informaci\u00f3n que queremos dar contiene muchos datos, la onda es mucho m\u00e1s delgada y picada, que es el caso del wifi, y entonces el problema es que llevan mucha informaci\u00f3n pero en la distancia el lenguaje se disipa, por lo que a cuatro o cinco metros se empieza a perder efectividad. Es como si dos personas hablan en el mismo idioma y en el mismo sitio, se establece comunicaci\u00f3n bidireccional sin dificultad, pero si hay una gran distancia, que ser\u00eda una menor longitud de onda, hay que gritar, y entonces se recorre a la modulaci\u00f3n para conseguir transmitir una mayor cantidad de datos a mayor distancia.<\/p>\n<p style=\"text-align: left;\">Adem\u00e1s, en este pa\u00eds tenemos un problema con las antenas de telefon\u00eda que es legislativo. En Catalunya est\u00e1n emitiendo a 21.000 microvatios (\u00b5W), y en Espa\u00f1a a 40.000, y tenemos que estar gritando para que todo el mundo lo oiga, pero si estamos cerca es inaguantable, mientras que en pa\u00edses como Austria no est\u00e1 permitido que la modulaci\u00f3n de las antenas sea mayor a 100 \u00b5W, pero hay much\u00edsimas, en cada tejado. En otros como Francia, B\u00e9lgica, Luxemburgo o Inglaterra el wifi ha sido eliminado de las bibliotecas y las escuelas p\u00fablicas, en cambio aqu\u00ed lo est\u00e1n implantando cada vez m\u00e1s. Si ponen una wifi sola y la tengo lejos, no pasa nada, pero si hay muchas repartidas y a mucha intensidad, es preocupante.<\/p>\n<p style=\"text-align: left;\"><strong>\u00a0<\/strong><strong>\u00bfQu\u00e9 significa \u2018vivir en modo avi\u00f3n\u2019, el t\u00edtulo de tu \u00faltimo libro?<\/strong><\/p>\n<p style=\"text-align: left;\">Es una filosof\u00eda de vida, aprender a saber aparcar las nuevas tecnolog\u00edas para reconectar contigo mismo. Es tener el m\u00f3vil en silencio cuando hablo con alguien, y estar solamente por esta persona, es estar pendiente de lo que pasa a nuestro alrededor, porque muchas veces estamos con el m\u00f3vil y no sabemos ni como le ha ido el d\u00eda a nuestra pareja o a nuestros padres. Nos estamos perdiendo muchas cosas.<\/p>\n<p style=\"text-align: left;\">Una de las cosas que con la juventud de hoy en d\u00eda se ha perdido es la esencia de la comunicaci\u00f3n. Tengo dos hijos adolescentes que est\u00e1n todo el d\u00eda delante de la maquinita, enviando WhatsApp, y se re\u00fanen y juegan en la tableta no s\u00e9 cu\u00e1ntas horas. Es la <em>mobofobia<\/em>, llegar a unos niveles de dependencia de \u2018\u2019c\u00f3rtame una mano antes que me saquen el m\u00f3vil\u2019\u2019, de ataques de p\u00e1nico si se lo quitan. Y esto necesita una limitaci\u00f3n, mis hijos tienen prohibid\u00edsimo llevarse el m\u00f3vil a la habitaci\u00f3n. Hay un m\u00ednimo de normas de higiene a nivel electromagn\u00e9tico que se tendr\u00edan que cumplir, hay que saber cortar. Yo cuando llego a casa pongo el m\u00f3vil en modo avi\u00f3n.<\/p>\n<p style=\"text-align: left;\"><strong>La llegada de los Smartphone es un fen\u00f3meno relativamente nuevo. \u00bfA\u00fan no hemos aprendido a hacer un buen uso?<\/strong><\/p>\n<p style=\"text-align: left;\">No hacemos un buen uso, hacemos un uso excesivo. Cuando compras un m\u00f3vil, las instrucciones del fabricante recomiendan que utilices los auriculares para hablar, y que no te pongas el tel\u00e9fono en la oreja m\u00e1s de dos minutos. Si no lo haces es tu responsabilidad. Nokia encarg\u00f3 un estudio sobre los efectos de los m\u00f3viles y luego no quisieron publicarlo. Hay unos 2000 estudios de Bioinitiative.org, de m\u00e9dicos y cient\u00edficos de alrededor del mundo que hablan de la influencia de los campos electromagn\u00e9ticos vinculados al c\u00e1ncer, el CREAL dijo que hab\u00eda muchos indicios de que el campo electromagn\u00e9tico fuera causa de posibles tumores cerebrales, el Colegio de Oftalm\u00f3logos ha dicho que las pantallas retro iluminadas de las tabletas matan c\u00e9lulas retinoicas, y nadie los escucha. Y hasta que no haya pasado m\u00e1s tiempo y haya habido v\u00edctimas esto no cambiar\u00e1. \u00bfCu\u00e1ntos a\u00f1os tardaron a decirnos que el tabaco era cancer\u00edgeno, que los rayos ultraviolados de las camas de bronceado provocan c\u00e1ncer de piel? El alcohol es una droga permitida y legal pero todos sabemos que beber mucho puede acabar con nuestra salud. Yo creo que el secreto est\u00e1 en la dosis, m\u00e1s que en el tiempo. La electrosensibilidad es la enfermedad del siglo XXI, hoy en d\u00eda todos somos electrosensibles porque nos afectan los campos electromagn\u00e9ticos, pero lo que cuesta es identificar ese efecto. Hay personas que tienen dolor de cabeza, mareos, agotamiento, cefaleas, micciones, pero como se muestran con s\u00edntomas que se mezclan con estados de \u00e1nimo, cuesta identificarlo.<\/p>\n<p style=\"text-align: left;\"><strong>\u00a0<\/strong><strong>En Espais Saludables tambi\u00e9n hac\u00e9is an\u00e1lisis de radiaciones naturales, a parte de las originadas por la tecnolog\u00eda. \u00bfEn qu\u00e9 consisten? <\/strong><\/p>\n<p style=\"text-align: left;\">Son las originarias provocadas por la tierra. La tierra tiene un n\u00facleo ferroso que es magn\u00e9tico y que extiende unas l\u00edneas de fuerza. Dentro del subsuelo hay materiales que son ferrosos y que por este magnetismo, son lugares altamente energ\u00e9ticos. Hay personas que se ven muy afectadas, las radiaciones naturales las debilitan y les atacan el sistema inmune, pero lo m\u00e1s frecuente son las geopat\u00edas, las enfermedades provocadas por la tierra, por aguas subterr\u00e1neas que circulan a mucha velocidad y que acostumbran a estar muy profundas. La fricci\u00f3n del agua con la tierra produce ionizaci\u00f3n (diferencia de potencial el\u00e9ctrico) y esto altera la producci\u00f3n de melatonina de la gl\u00e1ndula pineal de la persona que est\u00e9 durmiendo, de forma que todos los procesos biol\u00f3gicos que deber\u00eda hacer durante la noche no los hace, y acaba enfermando. Si est\u00e1s de seis a ocho a\u00f1os en una geopat\u00eda tienes muchos n\u00fameros de acabar con c\u00e1ncer. Mi estad\u00edstica son 3000 estudios, 12.000 camas vistas y 875 casos de c\u00e1ncer. Cuando llegue a los 5000 estudios voy a publicarla, espero tardar unos tres a\u00f1os.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfEl c\u00e1ncer es el tipo de enfermedad que m\u00e1s se detecta en estos casos?<\/strong><\/p>\n<p style=\"text-align: left;\">S\u00ed, porque es la consecuencia de que el sistema inmune no pueda luchar contra las agresiones. Somos m\u00e1quinas perfectas, y estamos fabricados para autorepararnos. Cuando estamos durmiendo no solo dormimos, tambi\u00e9n nos reparamos, nos damos cuerda, por eso es muy importante que sean ocho horas de calidad. Hay personas que cuando mueren se sabe, mediante autopsia, que han sufrido uno o dos o tres canceres, pero su organismo ha podido luchar contra ellos. Pero cuando una persona duerme mucho tiempo en un lugar inmunodepresivo, ya sea por radiaciones naturales o artificiales, y est\u00e1 sometida a un estr\u00e9s continuo, llega un momento que ya no aguanta m\u00e1s. Me he encontrado con que entre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfCu\u00e1les son los peores casos con los que te has encontrado?<\/strong><\/p>\n<p style=\"text-align: left;\">Hay muchos. Que tres personas hayan muerto de c\u00e1ncer en el mismo lugar, tener que hacer siete veces un estudio en la misma casa, que haya parejas que no consigan quedarse embarazadas o que hayan tenido abortamientos, y les mueves la cama de lugar y lo consiguen\u2026 En ciudades como Aiguafreda habr\u00e9 hecho m\u00e1s de ochenta estudios, y Andorra tambi\u00e9n es un pa\u00eds c\u00e1ncer porque hay muchas vetas de agua.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfC\u00f3mo es el proceso desde que detectas una radiaci\u00f3n natural?<\/strong><\/p>\n<p style=\"text-align: left;\">Normalmente lo hacemos a sensibilidad personal, con radiestesia, con varillas o con un p\u00e9ndulo, y cuando hacemos un terreno donde no hay campos el\u00e9ctricos alrededor, voy con un geomagnet\u00f3metro, un aparato muy complicado y muy lento que mide la diferencia de potencial el\u00e9ctrico de la tierra. Y entonces hacemos un test de quiniesolog\u00eda in situ con un testimonio.<\/p>\n<p style=\"text-align: left;\">Cuando detecto que una persona est\u00e1 en geopat\u00eda, con un sistema inmune muy bajo, la acompa\u00f1o a hacerse un test m\u00e9dico, yo colaboro con 17 m\u00e9dicos. Luego se le hace una prueba llamada Electroacupuntura de Voll y una Bioimpedancia para ver qu\u00e9 partes de su cuerpo est\u00e1n afectadas. La m\u00e1quina utilizada para este proceso, que est\u00e1 en muy pocos lugares, permite ver si hay alg\u00fan bloqueo en alg\u00fan \u00f3rgano o alguna falta vitam\u00ednica en alguna parte del cuerpo. Entonces se confirma si hay geopat\u00eda, el m\u00e9dico da la mediaci\u00f3n adecuada, se cambia la ubicaci\u00f3n de la cama de la persona y al cabo de un mes o dos vuelve al m\u00e9dico a comprobar si ha habido resultados. Pero as\u00ed es como me gusta trabajar a m\u00ed, porque a veces puedes encontrarte con personas esot\u00e9ricas.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfEn qu\u00e9 sentido?<\/strong><\/p>\n<p style=\"text-align: left;\">Que les ponen a la gente una manta de lana de oveja debajo de la cama y les dicen que eso va a cur\u00e1rselo todo, o utilizan cajas milagrosas, pegatinas, espejos o esculturas de yeso. Chorradas que son tomaduras de pelo y que les cuestan a la gente una aut\u00e9ntica fortuna. Hay personas que han pagado 3000 euros y les han colocado un trozo de madera pintada e impregnada de cera de abeja debajo de la cama, y la persona se lo traga y cree que mejora, pero no lo hace.<\/p>\n<p style=\"text-align: left;\"><strong>Si la pr\u00e1ctica est\u00e1 poco extendida, y no se acostumbra a hablar de ella, la gente no la conoce.<\/strong><\/p>\n<p style=\"text-align: left;\">S\u00ed que se habla de ella, pocos m\u00e9dicos tienen la m\u00e1quina de la Electroacupuntura de Voll, que es la \u00fanica prueba que da evidencia, adem\u00e1s de la moraterapia, pero la gran mayor\u00eda de oste\u00f3patas, acupuntores, home\u00f3patas y kinesi\u00f3logos saben verlo, lo que pasa es que, es muy triste pero, si yo soy martillo, solo veo clavos. Si un especialista ve que el paciente no puede dormir, le dar\u00e1 pastillas para dormir, en vez de preguntarle por qu\u00e9 no duerme. As\u00ed, los buenos m\u00e9dicos son los que son integrativos, los que tienen una visi\u00f3n mucho m\u00e1s amplia. Muchos m\u00e9dicos no me env\u00edan los pacientes hasta que lo han probado absolutamente todo, y luego a remontar y es espectacular. La parte triste de mi trabajo es que ayudas much\u00edsimas personas y no te lo dicen, y los m\u00e9dicos me dicen, \u2018\u2019tranquilo, <em>no news, good news\u2019\u2019<\/em>, pero es que solo me escriben cuando hay algo que no funciona.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfCu\u00e1nto hace que se sabe que hay relaci\u00f3n entre el impacto de las radiaciones y nuestra salud?<\/strong><\/p>\n<p style=\"text-align: left;\">Desde los a\u00f1os 30, con el doctor alem\u00e1n Ernst Hartmann y otros, pero que la influencia de la tierra altera la salud de las personas lo saben en China desde la aparici\u00f3n del Feng Shui y tambi\u00e9n lo sab\u00edan los romanos, que cuando ten\u00edan que poblar una ciudad dejaban a las ovejas pasturando y constru\u00edan las casas donde estas se pon\u00edan. Tambi\u00e9n las iglesias se edificaban en grandes corrientes de agua, porque como son lugares muy energ\u00e9ticos, consegu\u00edan atrapar la atenci\u00f3n de la gente.<\/p>\n<p style=\"text-align: left;\"><strong>Entonces, \u00bfpor qu\u00e9 a d\u00eda de hoy no hay reconocimiento pol\u00edtico y no se aplica en la construcci\u00f3n?<\/strong><\/p>\n<p style=\"text-align: left;\">En algunos pa\u00edses como Alemania lo hacen, all\u00ed es lo m\u00e1s natural del mundo. Como m\u00e1s civilizado y m\u00e1s cultura tiene el pa\u00eds, la pr\u00e1ctica est\u00e1 mucho m\u00e1s extendida. Nosotros, por desgracia, estamos en un pa\u00eds de lerdos, solo hay que ver quien nos gobierna, y desde fuera nos preguntan que qu\u00e9 nos pasa, que c\u00f3mo puede ser que coloquemos m\u00e1s wifis y que los coches contaminen m\u00e1s que nunca, que no podamos poner placas solares y ser autosuficientes cuando somos el pa\u00eds con m\u00e1s sol de Europa. Y no podemos desconectarnos de la red el\u00e9ctrica porque hay un monopolio.<\/p>\n<p style=\"text-align: left;\">En el sistema m\u00e9dico actual hay un m\u00e9dico por cada 5000 habitantes, y \u00bfc\u00f3mo va a atender bien un hombre, por mucha voluntad que tenga, con cinco minutos por paciente? Y al final acaban yendo a m\u00e9dicos particulares solo los que tienen poder adquisitivo. Nosotros nos encontramos con tres conflictos: el poder adquisitivo, el nivel cultural y el m\u00e9dico integrativo. Todo el colectivo de personas que atiendo tiene un nivel econ\u00f3mico y cultural elevado, con una amplitud de miras muy grande, que entiende estas cosas. Si vas a los que tienen un nivel cultural m\u00e1s bajo, que por desgracia es el 70% de la poblaci\u00f3n, no lo entienden, dicen que esto son chorradas y que no se lo creen.<\/p>\n<p style=\"text-align: left;\"><strong>T\u00fa mismo fuiste reacio al principio. \u00bfQu\u00e9 te hizo cambiar de opini\u00f3n?<\/strong><\/p>\n<p style=\"text-align: left;\">S\u00ed, no me lo cre\u00eda. Mis hijos y mi mujer dorm\u00edan mal. Cuando movimos la cama de mis hijos, empezaron a dormir muy bien, pero aun no me lo cre\u00eda, y entonces me puse a dormir en un lugar geop\u00e1tico, durante un a\u00f1o, y empec\u00e9 a sufrirlo yo. En 2006 cerr\u00e9 mi actividad de arquitectura, en este despacho pasamos de 14 trabajadores a los cinco de ahora, para dedicarme solo a esto.<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfPor tanto la \u00fanica forma es ver para creer?<\/strong><\/p>\n<p style=\"text-align: left;\">Por desgracia s\u00ed. En mi trabajo dedico cerca de un 75% en pedagog\u00eda, y el resto en pr\u00e1ctica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace diez a\u00f1os sal\u00eda al mercado el primer Iphone, un dispositivo que pocos podr\u00edan haber imaginado que cambiar\u00eda la sociedad de una forma tan radical como lo ha hecho. Hoy, Espa\u00f1a es l\u00edder mundial en cuota de penetraci\u00f3n de Smartphone. Organismos internacionales han alertado de los m\u00faltiples riesgos que comportan [&hellip;]<\/p>\n","protected":false},"author":77,"featured_media":11795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pere Le\u00f3n: &quot;Entre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado&quot; - Revista Rambla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revistarambla.com\/en\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pere Le\u00f3n: &quot;Entre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado&quot; - Revista Rambla\" \/>\n<meta property=\"og:description\" content=\"Hace diez a\u00f1os sal\u00eda al mercado el primer Iphone, un dispositivo que pocos podr\u00edan haber imaginado que cambiar\u00eda la sociedad de una forma tan radical como lo ha hecho. Hoy, Espa\u00f1a es l\u00edder mundial en cuota de penetraci\u00f3n de Smartphone. Organismos internacionales han alertado de los m\u00faltiples riesgos que comportan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revistarambla.com\/en\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Rambla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revistarambla\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-02T07:14:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T18:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"388\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laia Font\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revistarambla\" \/>\n<meta name=\"twitter:site\" content=\"@revistarambla\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laia Font\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/\"},\"author\":{\"name\":\"Laia Font\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/person\\\/074811fdb159459dc686aa6cb9e250e9\"},\"headline\":\"Pere Le\u00f3n: \u00abEntre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\u00bb\",\"datePublished\":\"2017-03-02T07:14:19+00:00\",\"dateModified\":\"2021-12-20T18:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/\"},\"wordCount\":3276,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/pereleon-01.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/\",\"name\":\"Pere Le\u00f3n: \\\"Entre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\\\" - Revista Rambla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/pereleon-01.jpg\",\"datePublished\":\"2017-03-02T07:14:19+00:00\",\"dateModified\":\"2021-12-20T18:54:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/pereleon-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/pereleon-01.jpg\",\"width\":388,\"height\":243},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.revistarambla.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pere Le\u00f3n: \u00abEntre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#website\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/\",\"name\":\"Revista Rambla Barcelona\",\"description\":\"Periodismo independiente\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revistarambla.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#organization\",\"name\":\"Revista Rambla\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/banner_rambla_1900x600_BB.png\",\"contentUrl\":\"https:\\\/\\\/www.revistarambla.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/banner_rambla_1900x600_BB.png\",\"width\":1900,\"height\":600,\"caption\":\"Revista Rambla\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revistarambla\\\/\",\"https:\\\/\\\/x.com\\\/revistarambla\",\"https:\\\/\\\/www.instagram.com\\\/revista_rambla\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/revista-rambla\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revistarambla.com\\\/#\\\/schema\\\/person\\\/074811fdb159459dc686aa6cb9e250e9\",\"name\":\"Laia Font\",\"description\":\"(Sabadell, 1995). Estudi\u00f3 Periodismo en la Universidad Aut\u00f3noma de Barcelona y escribe sobre cultura, g\u00e9nero y pol\u00edtica. Actualmente, trabaja como escritora, traductora y Community Manager \\\"freelance\\\".\",\"sameAs\":[\"https:\\\/\\\/mrmomo.es\\\/autor\\\/Laia_Font.htm\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/in\\\/laiafontme\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pere Le\u00f3n: \"Entre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\" - Revista Rambla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revistarambla.com\/en\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/","og_locale":"en_GB","og_type":"article","og_title":"Pere Le\u00f3n: \"Entre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\" - Revista Rambla","og_description":"Hace diez a\u00f1os sal\u00eda al mercado el primer Iphone, un dispositivo que pocos podr\u00edan haber imaginado que cambiar\u00eda la sociedad de una forma tan radical como lo ha hecho. Hoy, Espa\u00f1a es l\u00edder mundial en cuota de penetraci\u00f3n de Smartphone. Organismos internacionales han alertado de los m\u00faltiples riesgos que comportan [&hellip;]","og_url":"https:\/\/www.revistarambla.com\/en\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/","og_site_name":"Revista Rambla","article_publisher":"https:\/\/www.facebook.com\/revistarambla\/","article_published_time":"2017-03-02T07:14:19+00:00","article_modified_time":"2021-12-20T18:54:15+00:00","og_image":[{"width":388,"height":243,"url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-01.jpg","type":"image\/jpeg"}],"author":"Laia Font","twitter_card":"summary_large_image","twitter_creator":"@revistarambla","twitter_site":"@revistarambla","twitter_misc":{"Written by":"Laia Font","Estimated reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#article","isPartOf":{"@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/"},"author":{"name":"Laia Font","@id":"https:\/\/www.revistarambla.com\/#\/schema\/person\/074811fdb159459dc686aa6cb9e250e9"},"headline":"Pere Le\u00f3n: \u00abEntre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\u00bb","datePublished":"2017-03-02T07:14:19+00:00","dateModified":"2021-12-20T18:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/"},"wordCount":3276,"commentCount":0,"publisher":{"@id":"https:\/\/www.revistarambla.com\/#organization"},"image":{"@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-01.jpg","articleSection":["Actualidad"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/","url":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/","name":"Pere Le\u00f3n: \"Entre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\" - Revista Rambla","isPartOf":{"@id":"https:\/\/www.revistarambla.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#primaryimage"},"image":{"@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-01.jpg","datePublished":"2017-03-02T07:14:19+00:00","dateModified":"2021-12-20T18:54:15+00:00","breadcrumb":{"@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#primaryimage","url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-01.jpg","contentUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2017\/03\/pereleon-01.jpg","width":388,"height":243},{"@type":"BreadcrumbList","@id":"https:\/\/www.revistarambla.com\/pere-leon-entre-el-50-y-el-60-de-los-canceres-que-hemos-detectado-podrian-haberse-evitado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.revistarambla.com\/"},{"@type":"ListItem","position":2,"name":"Pere Le\u00f3n: \u00abEntre el 50% y el 60% de los c\u00e1nceres que hemos detectado podr\u00edan haberse evitado\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.revistarambla.com\/#website","url":"https:\/\/www.revistarambla.com\/","name":"Revista Rambla Barcelona","description":"Periodismo independiente","publisher":{"@id":"https:\/\/www.revistarambla.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revistarambla.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.revistarambla.com\/#organization","name":"Revista Rambla","url":"https:\/\/www.revistarambla.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.revistarambla.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2020\/09\/banner_rambla_1900x600_BB.png","contentUrl":"https:\/\/www.revistarambla.com\/wp-content\/uploads\/2020\/09\/banner_rambla_1900x600_BB.png","width":1900,"height":600,"caption":"Revista Rambla"},"image":{"@id":"https:\/\/www.revistarambla.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revistarambla\/","https:\/\/x.com\/revistarambla","https:\/\/www.instagram.com\/revista_rambla","https:\/\/es.linkedin.com\/company\/revista-rambla"]},{"@type":"Person","@id":"https:\/\/www.revistarambla.com\/#\/schema\/person\/074811fdb159459dc686aa6cb9e250e9","name":"Laia Font","description":"(Sabadell, 1995). Estudi\u00f3 Periodismo en la Universidad Aut\u00f3noma de Barcelona y escribe sobre cultura, g\u00e9nero y pol\u00edtica. Actualmente, trabaja como escritora, traductora y Community Manager \"freelance\".","sameAs":["https:\/\/mrmomo.es\/autor\/Laia_Font.htm\/","https:\/\/es.linkedin.com\/in\/laiafontme"]}]}},"_links":{"self":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/11794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/comments?post=11794"}],"version-history":[{"count":0,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/posts\/11794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/media\/11795"}],"wp:attachment":[{"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/media?parent=11794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/categories?post=11794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistarambla.com\/en\/wp-json\/wp\/v2\/tags?post=11794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}